{"id":3333,"date":"2025-10-24T16:32:16","date_gmt":"2025-10-24T14:32:16","guid":{"rendered":"https:\/\/frenzzi.it\/?post_type=product&#038;p=3333"},"modified":"2026-05-04T15:37:54","modified_gmt":"2026-05-04T13:37:54","slug":"repair-style","status":"publish","type":"product","link":"https:\/\/frenzzi.it\/it\/product\/repair-style\/","title":{"rendered":"Repair &#038; Style"},"content":{"rendered":"\n\t\t<div id=\"fws_6a97a23d48727\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row vc_row-o-equal-height vc_row-flex\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-2 vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 vc_col-xs-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t<div class=\"wpb_content_element\" data-interval=\"0\">\n\t\t<div class=\"wpb_wrapper tabbed clearfix\" data-style=\"material\" data-animation=\"fade\" data-spacing=\"default\" data-icon-size=\"24\" data-full-width-line=\"\" data-color-scheme=\"extra-color-2\" data-alignment=\"left\">\n\t\t\t<ul class=\"wpb_tabs_nav ui-tabs-nav clearfix\" role=\"tablist\"><li class=\"tab-item active-tab\"><a role=\"tab\" id=\"tab-title-consejos-de-uso\" href=\"#tab-consejos-de-uso\" aria-selected=\"true\" tabindex=\"0\" aria-controls=\"tab-consejos-de-uso\" class=\"active-tab\"><span>Consejos de uso<\/span><\/a><\/li><li class=\"tab-item\"><a role=\"tab\" id=\"tab-title-ingredientes\" href=\"#tab-ingredientes\" aria-selected=\"false\" tabindex=\"-1\" aria-controls=\"tab-ingredientes\" ><span>Ingredientes<\/span><\/a><\/li><li class=\"tab-item\"><a role=\"tab\" id=\"tab-title-composicion\" href=\"#tab-composicion\" aria-selected=\"false\" tabindex=\"-1\" aria-controls=\"tab-composicion\" ><span>Composici\u00f3n<\/span><\/a><\/li><\/ul>\n\n\t\t\t\n\t\t\t<div id=\"tab-consejos-de-uso\" role=\"tabpanel\" aria-labelledby=\"tab-title-consejos-de-uso\" tabindex=\"0\" data-tab-icon=\"\" class=\"wpb_tab ui-tabs-panel wpb_ui-tabs-hide clearfix\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p><strong>Paso 1: Maschera con Proteina di Riso<\/strong><br \/>\nApplica la maschera sui capelli bagnati e lascia agire per 5-10 minuti.<br \/>\n<em>Consiglio Extra:<\/em> Usa una cuffia da doccia per potenziare l&#8217;effetto.<\/p>\n<p><strong>Paso 2: Crema Districante ai Mirtilli<\/strong><br \/>\nApplica la crema sui capelli umidi per idratare e controllare il crespo mentre pettini.<\/p>\n<p><strong>Paso 3: Applicazione del Gel di Lino<\/strong><br \/>\nDistribuisci il gel sui capelli umidi per definire la capigliatura.<br \/>\n<em>Consiglio Extra:<\/em> Emulsionarlo tra le mani fino a creare una schiuma cremosa.<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t\t<div id=\"tab-ingredientes\" role=\"tabpanel\" aria-labelledby=\"tab-title-ingredientes\" tabindex=\"0\" data-tab-icon=\"\" class=\"wpb_tab ui-tabs-panel wpb_ui-tabs-hide clearfix\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p><strong>Maschera:<\/strong> Estratto di mirtilli, proteina di riso, olio di cocco.<\/p>\n<p><strong>Gel di Lino:<\/strong> Estratto di lino, oli essenziali, estratto di fiori di caprifoglio.<\/p>\n<p><strong>Crema Modellante:<\/strong> Olio di cocco, estratto di mirtilli.<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t\t<div id=\"tab-composicion\" role=\"tabpanel\" aria-labelledby=\"tab-title-composicion\" tabindex=\"0\" data-tab-icon=\"\" class=\"wpb_tab ui-tabs-panel wpb_ui-tabs-hide clearfix\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p><strong>Maschera Proteina di Riso:<\/strong><br \/>\n<strong>150ml<\/strong><br \/>\nAqua, Cetearyl alcohol, Hydrogenated coconut oil, Glycerin, Cetrimonium chloride, Glyceryl stearate SE, Ethylhexylglycerin, Parfum, Caprylyl glycol, Glyceryl caprylate\/caprate, Sodium gluconate, Sodium benzoate, Potassium sorbate, Hexyl cinnamal, Hydrolyzed rice protein, Vaccinium myrtillus fruit extract, Citric acid, Limonene, Hydroxycitronellal.<\/p>\n<p><strong>Gel di Lino:<\/strong><br \/>\n<strong>250ml<\/strong><br \/>\nAqua, Glycerin, Cetrimonium chloride, Hydroxyethylcellulose, Parfum, Pentylene glycol, Polyglyceryl-4 caprate, Polyglyceryl-6 caprylate, PVP, Lonicera caprifolium flower extract, Polyquaternium-7, Lonicera japonica flower extract, Linum usitatissimum seed extract, Honokiol, Linalool, Benzyl salicylate, Biosaccharide gum-4, Limonene, Caramel.<\/p>\n<p><strong>Crema Modellante Mirtilli:<\/strong><br \/>\n<strong>250ml<\/strong><br \/>\nAqua, Cetearyl alcohol, Glycerin, Ethylhexyl cocoate, Ceteareth-20, Polyquaternium-7, Parfum, Caprylyl glycol, Cocos nucifera oil, Glyceryl caprylate\/caprate, Cetrimonium chloride, Polyquaternium-10, Ethylhexylglycerin, Sodium benzoate, Hexyl cinnamal, Potassium sorbate, Vaccinium myrtillus fruit extract, Limonene, Biosaccharide gum-4, Hydroxycitronellal.<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div> \n\t<\/div> \n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97a23d4a60f\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-4 vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a97a23d4adc8\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-3 vc_col-xs-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"150\" width=\"150\" data-animation=\"none\" src=\"https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Vegan-Product-150x150.png\" alt=\"\" srcset=\"https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Vegan-Product-150x150.png 150w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Vegan-Product-300x300.png 300w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Vegan-Product-140x140.png 140w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Vegan-Product-100x100.png 100w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Vegan-Product-350x350.png 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 vc_col-xs-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"150\" width=\"150\" data-animation=\"none\" src=\"https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Gluten-Free-150x150.png\" alt=\"\" srcset=\"https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Gluten-Free-150x150.png 150w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Gluten-Free-300x300.png 300w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Gluten-Free-140x140.png 140w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Gluten-Free-100x100.png 100w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Gluten-Free-350x350.png 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 vc_col-xs-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"150\" width=\"150\" data-animation=\"none\" src=\"https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Paraben-Free-150x150.png\" alt=\"\" srcset=\"https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Paraben-Free-150x150.png 150w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Paraben-Free-300x300.png 300w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Paraben-Free-140x140.png 140w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Paraben-Free-100x100.png 100w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Paraben-Free-350x350.png 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 vc_col-xs-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"150\" width=\"150\" data-animation=\"none\" src=\"https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Silicon-Free-150x150.png\" alt=\"\" srcset=\"https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Silicon-Free-150x150.png 150w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Silicon-Free-300x300.png 300w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Silicon-Free-140x140.png 140w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Silicon-Free-100x100.png 100w, https:\/\/frenzzi.it\/wp-content\/uploads\/2021\/02\/Silicon-Free-350x350.png 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Un\u2019esperienza intensiva di riparazione e idratazione profonda. La maschera con proteine del riso rinforza e rivitalizza, la crema districante idrata e controlla il crespo, e il gel di lino fissa la definizione. Ideale per restaurare ricci e onde con morbidezza, elasticit\u00e0 e luminosit\u00e0 sana.<\/p>\n","protected":false},"featured_media":3334,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":["post-3333","product","type-product","status-publish","has-post-thumbnail","product_cat-kit","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/frenzzi.it\/it\/wp-json\/wp\/v2\/product\/3333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenzzi.it\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/frenzzi.it\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/frenzzi.it\/it\/wp-json\/wp\/v2\/comments?post=3333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenzzi.it\/it\/wp-json\/wp\/v2\/media\/3334"}],"wp:attachment":[{"href":"https:\/\/frenzzi.it\/it\/wp-json\/wp\/v2\/media?parent=3333"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/frenzzi.it\/it\/wp-json\/wp\/v2\/product_brand?post=3333"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/frenzzi.it\/it\/wp-json\/wp\/v2\/product_cat?post=3333"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/frenzzi.it\/it\/wp-json\/wp\/v2\/product_tag?post=3333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}